{"id":44536,"date":"2025-09-25T18:09:27","date_gmt":"2025-09-25T16:09:27","guid":{"rendered":"https:\/\/www.atelpi.com\/product\/hcl-lex-f035-035-w2-illuminatore-coassiale\/"},"modified":"2025-09-25T18:16:42","modified_gmt":"2025-09-25T16:16:42","slug":"hcl-lex-f035-035-w2-illuminatore-coassiale","status":"publish","type":"product","link":"https:\/\/www.atelpi.com\/it\/product\/hcl-lex-f035-035-w2-illuminatore-coassiale\/","title":{"rendered":"HCL-LEX-F035-035-W2 Illuminatore coassiale"},"content":{"rendered":"<p>Illuminatore coassiale Bianco SMD LED contenitore Alluminio dim.70x44x45 mm, dim.luce 35&#215;35 mm, dim.finestra 35&#215;35 mm, 24V, 4W, 330 g, Connettore SMR-03V-B, Conforme EN 62471, Conforme EN 55032 e EN 61000<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Illuminatore coassiale Bianco SMD LED contenitore Alluminio dim.70x44x45 mm, dim.luce 35&#215;35 mm, dim.finestra 35&#215;35 mm, 24V, 4W <BR><B> Consegna in 2 settimane se disponibile, 4 settimane se ordinabile<\/B><\/p>\n","protected":false},"featured_media":43342,"comment_status":"open","ping_status":"closed","template":"","meta":[],"etheme_brands":[{"term_id":1698,"name":"ATELPI","slug":"atelpi-it","term_group":0,"term_taxonomy_id":1698,"taxonomy":"brand","description":"","parent":0,"count":117,"filter":"raw"}],"product_brand":[],"product_cat":[6532,711,6533],"product_tag":[6534,2871,6453],"class_list":{"0":"post-44536","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"brand-atelpi-it","7":"product_cat-coassiali","8":"product_cat-illuminatori","9":"product_cat-hcl-lex-illuminatori-coassiali","10":"product_tag-coassiali","11":"product_tag-illuminatori","12":"product_tag-standard-2","13":"pa_altezza-mm-1675","14":"pa_colore-bianco","15":"pa_compliant-iso-15066-no","16":"pa_conforme-en-55032-e-en-61000-si","17":"pa_conforme-en-62471-si","18":"pa_conforme-iso-13732-1-no","19":"pa_connettore-smr-03v-b","20":"pa_elettronica-non-richiesta-opzionale","21":"pa_largh-finestra-mm-6463","22":"pa_largh-lum-mm-6461","23":"pa_lungh-finestra-mm-6462","24":"pa_lungh-lum-mm-6460","25":"pa_lunghezza-mm-5512","26":"pa_peso-g-6003","27":"pa_potenza-nominale-w-3358","28":"pa_profondita-mm-5989","29":"pa_stato-attivo","30":"pa_tecnologia-smd-led","31":"pa_tecnologia-del-supporto-alluminio","32":"pa_tensione-di-alimentazione-v-2225","33":"pa_tipo-illuminatore-coassiale","35":"first","36":"instock","37":"sale","38":"taxable","39":"shipping-taxable","40":"purchasable","41":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>HCL-LEX-F035-035-W2 Illuminatore coassiale - ATELPI<\/title>\n<meta name=\"description\" content=\"Illuminatore coassiale Bianco SMD LED contenitore Alluminio dim.70x44x45 mm, dim.luce 35x35 mm, dim.finestra 35x35 mm, 24V, 4W Consegna in 2 settimane se disponibile, 4 settimane se ordinabile\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.atelpi.com\/it\/product\/hcl-lex-f035-035-w2-illuminatore-coassiale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"HCL-LEX-F035-035-W2 Illuminatore coassiale - ATELPI\" \/>\n<meta property=\"og:description\" content=\"Illuminatore coassiale Bianco SMD LED contenitore Alluminio dim.70x44x45 mm, dim.luce 35x35 mm, dim.finestra 35x35 mm, 24V, 4W Consegna in 2 settimane se disponibile, 4 settimane se ordinabile\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.atelpi.com\/it\/product\/hcl-lex-f035-035-w2-illuminatore-coassiale\/\" \/>\n<meta property=\"og:site_name\" content=\"ATELPI\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-25T16:16:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.atelpi.com\/wp-content\/uploads\/HCL-LEX-F-2-web1-800q.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.atelpi.com\/it\/product\/hcl-lex-f035-035-w2-illuminatore-coassiale\/\",\"url\":\"https:\/\/www.atelpi.com\/it\/product\/hcl-lex-f035-035-w2-illuminatore-coassiale\/\",\"name\":\"HCL-LEX-F035-035-W2 Illuminatore coassiale - ATELPI\",\"isPartOf\":{\"@id\":\"https:\/\/www.atelpi.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.atelpi.com\/it\/product\/hcl-lex-f035-035-w2-illuminatore-coassiale\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.atelpi.com\/it\/product\/hcl-lex-f035-035-w2-illuminatore-coassiale\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.atelpi.com\/wp-content\/uploads\/HCL-LEX-F-2-web1-800q.webp\",\"datePublished\":\"2025-09-25T16:09:27+00:00\",\"dateModified\":\"2025-09-25T16:16:42+00:00\",\"description\":\"Illuminatore coassiale Bianco SMD LED contenitore Alluminio dim.70x44x45 mm, dim.luce 35x35 mm, dim.finestra 35x35 mm, 24V, 4W Consegna in 2 settimane se disponibile, 4 settimane se ordinabile\",\"breadcrumb\":{\"@id\":\"https:\/\/www.atelpi.com\/it\/product\/hcl-lex-f035-035-w2-illuminatore-coassiale\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.atelpi.com\/it\/product\/hcl-lex-f035-035-w2-illuminatore-coassiale\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.atelpi.com\/it\/product\/hcl-lex-f035-035-w2-illuminatore-coassiale\/#primaryimage\",\"url\":\"https:\/\/www.atelpi.com\/wp-content\/uploads\/HCL-LEX-F-2-web1-800q.webp\",\"contentUrl\":\"https:\/\/www.atelpi.com\/wp-content\/uploads\/HCL-LEX-F-2-web1-800q.webp\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.atelpi.com\/it\/product\/hcl-lex-f035-035-w2-illuminatore-coassiale\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.atelpi.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/www.atelpi.com\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"HCL-LEX-F035-035-W2 Illuminatore coassiale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.atelpi.com\/#website\",\"url\":\"https:\/\/www.atelpi.com\/\",\"name\":\"ATELPI\",\"description\":\"MACHINE VISION AUTOMATION\",\"publisher\":{\"@id\":\"https:\/\/www.atelpi.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.atelpi.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.atelpi.com\/#organization\",\"name\":\"ATELPI\",\"url\":\"https:\/\/www.atelpi.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.atelpi.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.atelpi.com\/wp-content\/uploads\/2024\/04\/logo-atelpi-msk-990x265-1.png\",\"contentUrl\":\"https:\/\/www.atelpi.com\/wp-content\/uploads\/2024\/04\/logo-atelpi-msk-990x265-1.png\",\"width\":990,\"height\":265,\"caption\":\"ATELPI\"},\"image\":{\"@id\":\"https:\/\/www.atelpi.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"HCL-LEX-F035-035-W2 Illuminatore coassiale - ATELPI","description":"Illuminatore coassiale Bianco SMD LED contenitore Alluminio dim.70x44x45 mm, dim.luce 35x35 mm, dim.finestra 35x35 mm, 24V, 4W Consegna in 2 settimane se disponibile, 4 settimane se ordinabile","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.atelpi.com\/it\/product\/hcl-lex-f035-035-w2-illuminatore-coassiale\/","og_locale":"it_IT","og_type":"article","og_title":"HCL-LEX-F035-035-W2 Illuminatore coassiale - ATELPI","og_description":"Illuminatore coassiale Bianco SMD LED contenitore Alluminio dim.70x44x45 mm, dim.luce 35x35 mm, dim.finestra 35x35 mm, 24V, 4W Consegna in 2 settimane se disponibile, 4 settimane se ordinabile","og_url":"https:\/\/www.atelpi.com\/it\/product\/hcl-lex-f035-035-w2-illuminatore-coassiale\/","og_site_name":"ATELPI","article_modified_time":"2025-09-25T16:16:42+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/www.atelpi.com\/wp-content\/uploads\/HCL-LEX-F-2-web1-800q.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.atelpi.com\/it\/product\/hcl-lex-f035-035-w2-illuminatore-coassiale\/","url":"https:\/\/www.atelpi.com\/it\/product\/hcl-lex-f035-035-w2-illuminatore-coassiale\/","name":"HCL-LEX-F035-035-W2 Illuminatore coassiale - ATELPI","isPartOf":{"@id":"https:\/\/www.atelpi.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.atelpi.com\/it\/product\/hcl-lex-f035-035-w2-illuminatore-coassiale\/#primaryimage"},"image":{"@id":"https:\/\/www.atelpi.com\/it\/product\/hcl-lex-f035-035-w2-illuminatore-coassiale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.atelpi.com\/wp-content\/uploads\/HCL-LEX-F-2-web1-800q.webp","datePublished":"2025-09-25T16:09:27+00:00","dateModified":"2025-09-25T16:16:42+00:00","description":"Illuminatore coassiale Bianco SMD LED contenitore Alluminio dim.70x44x45 mm, dim.luce 35x35 mm, dim.finestra 35x35 mm, 24V, 4W Consegna in 2 settimane se disponibile, 4 settimane se ordinabile","breadcrumb":{"@id":"https:\/\/www.atelpi.com\/it\/product\/hcl-lex-f035-035-w2-illuminatore-coassiale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.atelpi.com\/it\/product\/hcl-lex-f035-035-w2-illuminatore-coassiale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.atelpi.com\/it\/product\/hcl-lex-f035-035-w2-illuminatore-coassiale\/#primaryimage","url":"https:\/\/www.atelpi.com\/wp-content\/uploads\/HCL-LEX-F-2-web1-800q.webp","contentUrl":"https:\/\/www.atelpi.com\/wp-content\/uploads\/HCL-LEX-F-2-web1-800q.webp","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.atelpi.com\/it\/product\/hcl-lex-f035-035-w2-illuminatore-coassiale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.atelpi.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.atelpi.com\/shop\/"},{"@type":"ListItem","position":3,"name":"HCL-LEX-F035-035-W2 Illuminatore coassiale"}]},{"@type":"WebSite","@id":"https:\/\/www.atelpi.com\/#website","url":"https:\/\/www.atelpi.com\/","name":"ATELPI","description":"MACHINE VISION AUTOMATION","publisher":{"@id":"https:\/\/www.atelpi.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.atelpi.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.atelpi.com\/#organization","name":"ATELPI","url":"https:\/\/www.atelpi.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.atelpi.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.atelpi.com\/wp-content\/uploads\/2024\/04\/logo-atelpi-msk-990x265-1.png","contentUrl":"https:\/\/www.atelpi.com\/wp-content\/uploads\/2024\/04\/logo-atelpi-msk-990x265-1.png","width":990,"height":265,"caption":"ATELPI"},"image":{"@id":"https:\/\/www.atelpi.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.atelpi.com\/it\/wp-json\/wp\/v2\/product\/44536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.atelpi.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.atelpi.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.atelpi.com\/it\/wp-json\/wp\/v2\/comments?post=44536"}],"version-history":[{"count":0,"href":"https:\/\/www.atelpi.com\/it\/wp-json\/wp\/v2\/product\/44536\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.atelpi.com\/it\/wp-json\/wp\/v2\/media\/43342"}],"wp:attachment":[{"href":"https:\/\/www.atelpi.com\/it\/wp-json\/wp\/v2\/media?parent=44536"}],"wp:term":[{"taxonomy":"brand","embeddable":true,"href":"https:\/\/www.atelpi.com\/it\/wp-json\/wp\/v2\/etheme_brands?post=44536"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.atelpi.com\/it\/wp-json\/wp\/v2\/product_brand?post=44536"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.atelpi.com\/it\/wp-json\/wp\/v2\/product_cat?post=44536"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.atelpi.com\/it\/wp-json\/wp\/v2\/product_tag?post=44536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}